{"id":34016,"date":"2022-06-01T15:00:00","date_gmt":"2022-06-01T19:00:00","guid":{"rendered":"https:\/\/chiropractic.ca\/?p=34016"},"modified":"2023-03-21T11:13:24","modified_gmt":"2023-03-21T15:13:24","slug":"6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/","title":{"rendered":"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate"},"content":{"rendered":"\n<figure class=\"wp-block-image is-resized\"><img decoding=\"async\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\" alt=\"les maux de t&#xEA;te\" class=\"wp-image-56568\" width=\"1280\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg 800w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-400x289.jpg 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-768x555.jpg 768w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-357x258.jpg 357w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-138x100.jpg 138w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-144x104.jpg 144w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-252x182.jpg 252w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-352x254.jpg 352w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-115x83.jpg 115w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3-700x506.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes. Cette clart\u00e9 d\u2019esprit peut facilement dispara\u00eetre en cas de violent mal de t\u00eate. Bien des gens souffrent de c\u00e9phal\u00e9es occasionnelles, mais les maux de t\u00eate fr\u00e9quents qui nuisent au sommeil ou aux t\u00e2ches quotidiennes peuvent \u00eatre invalidants.<\/p>\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #007392;\"><strong>Types de c\u00e9phal\u00e9es <\/strong><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Les types de maux de t\u00eate les plus courants sont les c\u00e9phal\u00e9es de tension.<\/p>\n\n<p class=\"wp-block-paragraph\">Les types de maux de t\u00eate les plus courants sont les c\u00e9phal\u00e9es de tension, qui peuvent causer des douleurs dans toutes les zones de la t\u00eate, et les migraines, qui s\u2019accompagnent de naus\u00e9es et d\u2019une sensibilit\u00e9 \u00e0 la lumi\u00e8re et au bruit.<\/p>\n\n<p class=\"wp-block-paragraph\">Dans les c\u00e9phal\u00e9es cervicog\u00e8nes, le cou est \u00e0 l&#8217;origine du probl\u00e8me mais la douleur est per\u00e7ue dans une ou plusieurs zones de la t\u00eate et\/ou du visage. Les causes des c\u00e9phal\u00e9es sont parfois difficiles \u00e0 cerner, mais les ant\u00e9c\u00e9dents familiaux, les raideurs cervicales et le stress sont des facteurs courants.<\/p>\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #007392;\"><strong>Comment la chiropratique peut-elle aider \u00e0 g\u00e9rer les maux de t\u00eate? <\/strong><\/span><\/h3>\n\n<p class=\"wp-block-paragraph\">Les chiropraticiens peuvent \u00e9valuer, diagnostiquer et traiter les c\u00e9phal\u00e9es. Les donn\u00e9es actuelles indiquent que les soins chiropratiques, notamment la th\u00e9rapie manuelle, peuvent \u00eatre efficaces pour traiter les c\u00e9phal\u00e9es cervicog\u00e8nes et les c\u00e9phal\u00e9es de tension. Des \u00e9tudes ont \u00e9galement d\u00e9montr\u00e9 que les soins chiropratiques peuvent contribuer \u00e0 att\u00e9nuer l\u2019intensit\u00e9 et la fr\u00e9quence des migraines. Les options de traitement sont, entre autres, les suivantes :<\/p>\n\n<ol class=\"wp-block-list\"><li>Th\u00e9rapie manuelle<\/li><li>Th\u00e9rapie des tissus mous<\/li><li>Applications telles qu\u2019\u00e9lectrostimulation, acupuncture et ultrasons<\/li><li>R\u00e9adaptation<\/li><li>Changements de mode de vie et \u00e9ducation<\/li><li>Orientation vers un sp\u00e9cialiste et cotraitement<\/li><\/ol>\n\n<p class=\"wp-block-paragraph\">Les c\u00e9phal\u00e9es doivent \u00eatre prises au s\u00e9rieux. <a href=\"https:\/\/chiropractic.ca\/fr\/trouvez-un-chiropraticien\/\">Consultez en chiropratique<\/a> si vous \u00e9prouvez de fr\u00e9quents maux de t\u00eate, si vous prenez fr\u00e9quemment des analg\u00e9siques pour vos maux de t\u00eate, si vous notez des changements dans la nature de vos c\u00e9phal\u00e9es ou si vos maux de t\u00eate s\u2019aggravent. Il est d\u2019autant plus important de consulter rapidement si vos c\u00e9phal\u00e9es sont soudaines et intenses, si elles font suite \u00e0 une blessure \u00e0 la t\u00eate ou si elles s\u2019accompagnent de fi\u00e8vre, d\u2019une raideur au cou, d\u2019une faiblesse, d\u2019engourdissements ou de difficult\u00e9 \u00e0 parler.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-palette-color-6-color has-alpha-channel-opacity has-palette-color-6-background-color has-background is-style-wide\"\/>\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\">R\u00c9F\u00c9RENCES<\/h3>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><span class='footnote' id='fn-34016-1'><a href='#fnref-34016-1'>1<\/a>.<\/span> Bryans R, Descarreaux M, Duranleau M, Marcoux H, Potter B, Ruegg R, Shaw L, Watkin R, White E. Evidence-based guidelines for the chiropractic treatment of adults with headache. <em>J Manipulative Physiol Ther<\/em>. 2011;34(5):274-89.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les chiropraticiens peuvent \u00e9valuer, diagnostiquer et traiter les c\u00e9phal\u00e9es. Les donn\u00e9es actuelles indiquent que les soins chiropratiques, notamment la th\u00e9rapie manuelle, peuvent \u00eatre efficaces pour traiter les c\u00e9phal\u00e9es cervicog\u00e8nes et les c\u00e9phal\u00e9es de tension.<\/p>\n","protected":false},"author":13561,"featured_media":56569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"71551,71846,69307,71837,67228,71852","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3122],"tags":[2933],"class_list":["post-34016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expertise-chiropratique","tag-chiropratique-au-canada"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sysadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sysadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/\"},\"author\":{\"name\":\"sysadmin\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\"},\"headline\":\"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate\",\"datePublished\":\"2022-06-01T19:00:00+00:00\",\"dateModified\":\"2023-03-21T15:13:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\",\"keywords\":[\"Chiropratique au Canada\"],\"articleSection\":[\"expertise chiropratique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/\",\"name\":\"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\",\"datePublished\":\"2022-06-01T19:00:00+00:00\",\"dateModified\":\"2023-03-21T15:13:24+00:00\",\"description\":\"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/canadian-chiropractic-association-headaches-and-migraines-3.jpg\",\"width\":800,\"height\":578,\"caption\":\"Headaches and Migraines\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/lacc-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"expertise chiropratique\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/category\\\/expertise-chiropratique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\",\"name\":\"sysadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/","og_locale":"fr_FR","og_type":"article","og_title":"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate - Association chiropratique canadienne","og_description":"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.","og_url":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2022-06-01T19:00:00+00:00","article_modified_time":"2023-03-21T15:13:24+00:00","og_image":[{"width":800,"height":578,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg","type":"image\/jpeg"}],"author":"sysadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sysadmin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/"},"author":{"name":"sysadmin","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff"},"headline":"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate","datePublished":"2022-06-01T19:00:00+00:00","dateModified":"2023-03-21T15:13:24+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/"},"wordCount":482,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg","keywords":["Chiropratique au Canada"],"articleSection":["expertise chiropratique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/","url":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/","name":"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg","datePublished":"2022-06-01T19:00:00+00:00","dateModified":"2023-03-21T15:13:24+00:00","description":"\u00catre capable d\u2019avoir une pens\u00e9e claire et de r\u00e9fl\u00e9chir calmement nous permet de prendre des d\u00e9cisions, de vivre nos \u00e9motions et de mener nos activit\u00e9s quotidiennes.","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2017\/12\/canadian-chiropractic-association-headaches-and-migraines-3.jpg","width":800,"height":578,"caption":"Headaches and Migraines"},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/6-moyens-dont-la-chiropratique-peut-aider-a-gerer-les-maux-de-tete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/lacc-2\/"},{"@type":"ListItem","position":2,"name":"expertise chiropratique","item":"https:\/\/chiropractic.ca\/fr\/category\/expertise-chiropratique\/"},{"@type":"ListItem","position":3,"name":"6 moyens dont la chiropratique peut aider \u00e0 g\u00e9rer les maux de t\u00eate"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff","name":"sysadmin"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/34016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/13561"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=34016"}],"version-history":[{"count":9,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/34016\/revisions"}],"predecessor-version":[{"id":72048,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/34016\/revisions\/72048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/56569"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=34016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=34016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=34016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}