{"id":67237,"date":"2022-10-14T12:00:00","date_gmt":"2022-10-14T16:00:00","guid":{"rendered":"https:\/\/chiropractic.ca\/?p=67237"},"modified":"2023-03-21T11:06:07","modified_gmt":"2023-03-21T15:06:07","slug":"la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/","title":{"rendered":"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg\" alt=\"Chiropraticien avec un patient\" class=\"wp-image-67233\" width=\"1000\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg 800w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system-400x289.jpg 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system-768x555.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le terme g\u00e9n\u00e9rique COVID de longue dur\u00e9e sert autant \u00e0 d\u00e9crire l\u2019infection aigu\u00eb \u00e0 la COVID-19 que les sympt\u00f4mes r\u00e9siduels post-COVID-19 qui durent plus de quatre semaines<sup>1<\/sup> et qu\u2019on ne saurait expliquer par un autre diagnostic. \u00c0 l\u2019image de la p\u00e9riode infectieuse de la COVID-19, les signes et sympt\u00f4mes de la COVID de longue dur\u00e9e se situent sur un spectre et peuvent aller d\u2019une toux r\u00e9siduelle l\u00e9g\u00e8re \u00e0 des sympt\u00f4mes plus graves, comme des difficult\u00e9s respiratoires, un essoufflement et des l\u00e9sions nerveuses ou musculaires. Sur ce spectre, jusqu\u2019\u00e0 65 % des patients ressentent des sympt\u00f4mes d\u2019ordre musculosquelettique<sup>1<\/sup>, p. ex., de la fatigue musculaire (49,1 %), de la myalgie ou des douleurs musculaires (34,8 %), et de l\u2019arthralgie ou des douleurs articulaires (33 %)<sup>2<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9cel\u00e9es dans des \u00e9tudes r\u00e9centes, des tendances d\u00e9montrent que les personnes appartenant \u00e0 certains groupes sont plus susceptibles de souffrir de douleurs musculosquelettiques apr\u00e8s avoir contract\u00e9 la COVID-19, notamment les femmes, les personnes \u00e2g\u00e9es, les personnes qui ont un indice de masse corporelle \u00e9lev\u00e9 ou qui souffrent de myalgie au moment de leur hospitalisation en raison de la COVID-19, les personnes qui ont des comorbidit\u00e9s et celles qui avaient des capacit\u00e9s physiques ou fonctionnelles r\u00e9duites avant d\u2019\u00eatre infect\u00e9es<sup>1<\/sup>. D\u2019autres \u00e9tudes signalent une force musculaire r\u00e9duite<sup>3<\/sup>, des affections caract\u00e9ris\u00e9es par une fatigue chronique<sup>4<\/sup> et, dans les cas graves, la d\u00e9gradation progressive des fibres musculaires<sup>5<\/sup>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes. Voici comment :<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">es chiropraticiens sont form\u00e9s pour d\u00e9terminer les causes potentielles des troubles musculosquelettiques, mais surtout le meilleur choix de traitement en pr\u00e9sence de tels troubles. Des travaux de recherche d\u00e9montrent l\u2019efficacit\u00e9 de certaines formes de traitements manuels et des tissus mous. Ces derniers permettent d\u2019orienter le flux sanguin vers les zones bless\u00e9es et de favoriser la gu\u00e9rison, tout en soulageant la pression articulaire et en r\u00e9initialisant les r\u00e9cepteurs de la douleur<sup>6,7<\/sup>. Habituellement, une ou plusieurs des approches pratiques utilis\u00e9es par les chiropraticiens contribuent \u00e0 soulager la douleur, et ce, quelle qu\u2019en soit la cause.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les chiropraticiens sont extr\u00eamement vers\u00e9s dans l\u2019application d\u2019une foule de traitements d\u2019appoint, y compris des modalit\u00e9s comme la neurostimulation \u00e9lectrique transcutan\u00e9e (TENS), le courant interf\u00e9rentiel (ICF), les th\u00e9rapies par ondes de choc et les phototh\u00e9rapies de faible intensit\u00e9. Or, au nombre de leurs effets, ces traitements comptent \u00e9galement le soulagement de la douleur et la gu\u00e9rison<sup>8-11<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019on s\u2019attaque aux sympt\u00f4mes de la COVID de longue dur\u00e9e, le traitement physique \u00e0 domicile ou supervis\u00e9 fourni par le chiropraticien doit faire l\u2019objet de consid\u00e9rations cliniques. Celles-ci portent notamment sur le type de traitement, sa fr\u00e9quence et la fa\u00e7on dont il est administr\u00e9. Par exemple, apr\u00e8s une analyse des ant\u00e9c\u00e9dents et un examen physique complets, le chiropraticien peut cr\u00e9er un plan de traitement combinant des th\u00e9rapies manuelles, des modalit\u00e9s et des exercices de r\u00e9adaptation selon les besoins individuels de chaque patient. Il est toutefois possible qu\u2019il conseille \u00e0 un patient qui souffre de douleurs musculaires et articulaires li\u00e9es \u00e0 la COVID de longue dur\u00e9e de faire des mouvements mod\u00e9r\u00e9s dans le cadre de la r\u00e9adaptation pour permettre \u00e0 son syst\u00e8me musculosquelettique de s\u2019adapter et de gu\u00e9rir efficacement. Dans certains cas, d\u2019autres mesures peuvent \u00eatre n\u00e9cessaires, p. ex., le recours \u00e0 un oxym\u00e8tre de pouls pour surveiller le taux d\u2019oxyg\u00e8ne durant un exercice<a>.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outre la r\u00e9adaptation \u00e0 l\u2019activit\u00e9 physique et la gestion de la douleur, les chiropraticiens peuvent sugg\u00e9rer \u00e0 leurs patients des techniques pour conserver leur \u00e9nergie dans le cadre de leurs activit\u00e9s quotidiennes ou des exercices th\u00e9rapeutiques physiques. Dans le m\u00eame ordre d\u2019id\u00e9es, ils peuvent recommander des strat\u00e9gies ergonomiques qui facilitent les t\u00e2ches essentielles au travail ou \u00e0 la maison. Un chiropraticien que l\u2019on consulte comme membre \u00e0 part enti\u00e8re d\u2019une \u00e9quipe de soins de sant\u00e9 peut \u00e9galement assumer le r\u00f4le de personne-ressource pour faire le suivi du patient en surveillant son \u00e9volution ou en lui faisant des recommandations \u00e9crites lorsqu\u2019un examen plus pouss\u00e9 s\u2019impose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/chiropractic.ca\/about-chiropractic\/find-a-chiro\/\" style=\"border-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener\">Trouvez un chiropraticien pr\u00e8s de chez vous.<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9f\u00e9rences :<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">[1] Khoja, O., et al. Clinical characteristics and mechanisms of musculoskeletal pain in long COVID. J Pain Res. 2022 Jun; 15:1729-48.  <br>[2] Tharani, SA., and Borkar, P. Prevalence of musculoskeletal disorders in post-COVID-19 patients \u2013 a systematic review. Int J Health Sci Res. 2022 Mar; 12(3):374-80.<br>[3] Hasan LK., et al. Effects of COVID-19 on the musculoskeletal system: a clinician\u2019s guide. Orth Res Rev. 2021 Sep; 13:141-50.<br>[4] Crook H., et al. Long COVID \u2013 mechanisms, risk factors and management. BMJ. 2021 Jul; 374:n1648.   <br>[5] Dos Santos, PK., et al. The musculoskeletal involvement after mild to moderate COVID-19 infection. Front Phys. 2022 Mar; 13:813924.<br>[6] Bialosky JE., et al. The mechanisms of manual therapy in the treatment of musculoskeletal pain: a comprehensive model. Man Ther. 2010 Oct: 14(5):531-38.<br>[7] Ajimsha MS., et al. Effectiveness of myofascial release: systematic review of randomized controlled trials. J Bodyw Mov Ther. 2015 Jan; 19(1):102-12.<br>[8] DeSantana, JM., et al. Effectiveness of transcutaneous electrical nerve stimulation for treatment of hyperalgesia and pain. Curr Rheumatol Rep. 2008 Dec; 10(6):492-99.<br>[9] Fuentes, JP., et al. Effectiveness of interferential current therapy in the management of musculoskeletal pain: a systematic review and meta-analysis. Phys Ther. 2010 Sep; 90(9): 1219-38.<br>[10] Schmitz, C., et al. Efficacy and safety of extracorporeal shock wave therapy for orthopedic conditions: a systematic review on studies listed in the PEDro database. Br Med Bull. 2015 Nov; 116(1): 115-38.   <br>[11] Clijsen, R., et al. Effects of low-level laser therapy on pain in patients with musculoskeletal disorders: a systematic review and meta-analysis. Eu J Phys Rehab Med. 2017 Jan; 53(4):603-10.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le terme g\u00e9n\u00e9rique COVID de longue dur\u00e9e sert autant \u00e0 d\u00e9crire l\u2019infection aigu\u00eb \u00e0 la COVID-19 que les sympt\u00f4mes r\u00e9siduels post-COVID-19 qui durent plus de quatre semaines1 et qu\u2019on ne saurait expliquer par un autre diagnostic. \u00c0 l\u2019image de la p\u00e9riode infectieuse de la COVID-19, les signes et sympt\u00f4mes de la COVID de longue dur\u00e9e [&hellip;]<\/p>\n","protected":false},"author":13561,"featured_media":67234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"67228,29930,39950,17869,20473,47813","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3122],"tags":[2933,2485,2482],"class_list":["post-67237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expertise-chiropratique","tag-chiropratique-au-canada","tag-gestion-de-la-douleur","tag-soins-chiropratiques"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique? - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sysadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sysadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/\"},\"author\":{\"name\":\"sysadmin\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\"},\"headline\":\"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique?\",\"datePublished\":\"2022-10-14T16:00:00+00:00\",\"dateModified\":\"2023-03-21T15:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/\"},\"wordCount\":1033,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/long-covid-muculoskeletal-system.jpg\",\"keywords\":[\"Chiropratique au Canada\",\"Gestion De La Douleur\",\"Soins Chiropratiques\"],\"articleSection\":[\"expertise chiropratique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/\",\"name\":\"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique? - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/long-covid-muculoskeletal-system.jpg\",\"datePublished\":\"2022-10-14T16:00:00+00:00\",\"dateModified\":\"2023-03-21T15:06:07+00:00\",\"description\":\"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/long-covid-muculoskeletal-system.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/long-covid-muculoskeletal-system.jpg\",\"width\":800,\"height\":578,\"caption\":\"Chiropractor with a patient\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"expertise chiropratique\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/category\\\/expertise-chiropratique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\",\"name\":\"sysadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/","og_locale":"fr_FR","og_type":"article","og_title":"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique? - Association chiropratique canadienne","og_description":"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.","og_url":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2022-10-14T16:00:00+00:00","article_modified_time":"2023-03-21T15:06:07+00:00","og_image":[{"width":800,"height":578,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg","type":"image\/jpeg"}],"author":"sysadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sysadmin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/"},"author":{"name":"sysadmin","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff"},"headline":"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique?","datePublished":"2022-10-14T16:00:00+00:00","dateModified":"2023-03-21T15:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/"},"wordCount":1033,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg","keywords":["Chiropratique au Canada","Gestion De La Douleur","Soins Chiropratiques"],"articleSection":["expertise chiropratique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/","url":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/","name":"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique? - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg","datePublished":"2022-10-14T16:00:00+00:00","dateModified":"2023-03-21T15:06:07+00:00","description":"Si vous ressentez des douleurs musculaires ou articulaires r\u00e9siduelles apr\u00e8s avoir contract\u00e9 la COVID-19, un chiropraticien peut vous aider \u00e0 att\u00e9nuer vos sympt\u00f4mes.","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/10\/long-covid-muculoskeletal-system.jpg","width":800,"height":578,"caption":"Chiropractor with a patient"},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/la-covid-de-longue-duree-peut-elle-avoir-un-effet-sur-le-systeme-musculosquelettique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"expertise chiropratique","item":"https:\/\/chiropractic.ca\/fr\/category\/expertise-chiropratique\/"},{"@type":"ListItem","position":3,"name":"La COVID de longue dur\u00e9e peut-elle avoir un effet sur le syst\u00e8me musculosquelettique?"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff","name":"sysadmin"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/67237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/13561"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=67237"}],"version-history":[{"count":3,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/67237\/revisions"}],"predecessor-version":[{"id":71554,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/67237\/revisions\/71554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/67234"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=67237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=67237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=67237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}