{"id":71786,"date":"2022-09-01T10:00:00","date_gmt":"2022-09-01T14:00:00","guid":{"rendered":"https:\/\/chiropractic.ca\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/"},"modified":"2023-03-21T11:06:37","modified_gmt":"2023-03-21T15:06:37","slug":"les-soins-chiropratiques-favorisent-un-vieillissement-en-sante","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/","title":{"rendered":"Les soins chiropratiques favorisent un vieillissement en sant\u00e9"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"480\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/11\/chiropractic-blog-banner-healthy-aging.jpg\" alt=\"\" class=\"wp-image-70991\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/11\/chiropractic-blog-banner-healthy-aging.jpg 1024w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/11\/chiropractic-blog-banner-healthy-aging-400x188.jpg 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/11\/chiropractic-blog-banner-healthy-aging-768x360.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Au Canada, l\u2019esp\u00e9rance de vie moyenne ne cesse d\u2019augmenter. Elle se situe actuellement \u00e0 80 ans pour les hommes et \u00e0 84 ans pour les femmes<sup class='footnote' id='fnref-71786-1'><a href='#fn-71786-1' rel='footnote'>1<\/a><\/sup>. Toutefois, les Canadiens vivent-ils en vieillissant une vie pleine, active et en sant\u00e9 ? En r\u00e9alit\u00e9, en vieillissant, la sant\u00e9, la qualit\u00e9 de vie et l\u2019autonomie reposent sur une vie active. Le maintien de la forme physique et de la mobilit\u00e9 contribue \u00e0 pr\u00e9venir les probl\u00e8mes chroniques qui affectent trop souvent les a\u00een\u00e9s. En fait, m\u00eame un niveau d\u2019activit\u00e9 physique mod\u00e9r\u00e9 peut am\u00e9liorer l\u2019\u00e9quilibre, l\u2019endurance et la solidit\u00e9 des os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9. Les chiropracticiens peuvent \u00e9valuer votre force, votre mobilit\u00e9, vos fonctions et votre \u00e9quilibre ; ils peuvent vous conseiller des exercices, un plan nutritionnel et des strat\u00e9gies pr\u00e9ventives. Une population vieillissante risque davantage de souffrir des affections suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arthrose \u2013 la d\u00e9t\u00e9rioration des cartilages articulaires<\/li>\n\n\n\n<li>St\u00e9nose vert\u00e9brale \u2013 la compression des racines nerveuses provoqu\u00e9e par un r\u00e9tr\u00e9cissement du canal vert\u00e9bral, qui provoque douleur et engourdissement<\/li>\n\n\n\n<li>L\u00e9sion m\u00e9niscale d\u00e9g\u00e9n\u00e9rative<\/li>\n\n\n\n<li>Blessures d\u2019usure<\/li>\n\n\n\n<li>Ost\u00e9oporose \u2013 une maladie qui se caract\u00e9rise par la diminution de la masse osseuse et la d\u00e9t\u00e9rioration du tissu osseux<\/li>\n<\/ul>\n\n\n\n<h3 class=\"has-palette-color-1-color has-text-color wp-block-heading\">Nos experts vous aident<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Soulagement de la douleur<\/li>\n\n\n\n<li>Am\u00e9lioration de l\u2019amplitude de mouvement et des fonctions<\/li>\n\n\n\n<li>Ralentissement de la progression de la d\u00e9g\u00e9n\u00e9rescence articulaire<\/li>\n\n\n\n<li>Correction de la posture<\/li>\n\n\n\n<li>Am\u00e9lioration de l\u2019\u00e9quilibre<\/li>\n\n\n\n<li>Diminution des risques de chute<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-palette-color-6-color has-alpha-channel-opacity has-palette-color-6-background-color has-background is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00c9F\u00c9RENCES<\/h3>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><span class='footnote' id='fn-71786-1'><a href='#fnref-71786-1'>1<\/a>.<\/span> Organisation mondiale de la sant\u00e9. (2014). Statistiques sanitaires mondiales. (2014). Statistiques sanitaires mondiales.<br><span class='footnote' id='fn-71786-2'><a href='#fnref-71786-2'>2<\/a>.<\/span> Organisation mondiale de la sant\u00e9. (2008). Rapport mondial sur la pr\u00e9vention des chutes chez les personnes \u00e2g\u00e9es. Gen\u00e8ve : Organisation mondiale de la sant\u00e9. (2008). Global Report on Falls Prevention in Older Age. Geneva: World Health Organization.<br><span class='footnote' id='fn-71786-3'><a href='#fnref-71786-3'>3<\/a>.<\/span> Scott, V., Peck, S. &amp; Kendall, P. (2004). Prevention of Falls and Injuries Among the Elderly: A Special Report from the Office of the Provincial Health Officer. Victoria BC: Provincial Health Office, BC Ministry of Health Services Victoria BC: Provincial Health Office, BC Ministry of Health Services<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9. <\/p>\n","protected":false},"author":13561,"featured_media":70994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"71551,67228,71572,69307,71579,71582","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3187],"tags":[2933,2485,2482,2996],"class_list":["post-71786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vieillir-en-sante","tag-chiropratique-au-canada","tag-gestion-de-la-douleur","tag-soins-chiropratiques","tag-vieillir-en-sante"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les soins chiropratiques favorisent un vieillissement en sant\u00e9 - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-01T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:06:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sysadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sysadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/\"},\"author\":{\"name\":\"sysadmin\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\"},\"headline\":\"Les soins chiropratiques favorisent un vieillissement en sant\u00e9\",\"datePublished\":\"2022-09-01T14:00:00+00:00\",\"dateModified\":\"2023-03-21T15:06:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/\"},\"wordCount\":402,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chiropractic-blog-banner-healthy-aging.jpg\",\"keywords\":[\"Chiropratique au Canada\",\"Gestion De La Douleur\",\"Soins Chiropratiques\",\"vieillir en sant\u00e9\"],\"articleSection\":[\"Vieillir en sant\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/\",\"name\":\"Les soins chiropratiques favorisent un vieillissement en sant\u00e9 - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chiropractic-blog-banner-healthy-aging.jpg\",\"datePublished\":\"2022-09-01T14:00:00+00:00\",\"dateModified\":\"2023-03-21T15:06:37+00:00\",\"description\":\"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chiropractic-blog-banner-healthy-aging.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chiropractic-blog-banner-healthy-aging.jpg\",\"width\":1024,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vieillir en sant\u00e9\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/category\\\/vieillir-en-sante\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les soins chiropratiques favorisent un vieillissement en sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\",\"name\":\"sysadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Les soins chiropratiques favorisent un vieillissement en sant\u00e9 - Association chiropratique canadienne","og_description":"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.","og_url":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2022-09-01T14:00:00+00:00","article_modified_time":"2023-03-21T15:06:37+00:00","og_image":[{"width":1024,"height":480,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg","type":"image\/jpeg"}],"author":"sysadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sysadmin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/"},"author":{"name":"sysadmin","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff"},"headline":"Les soins chiropratiques favorisent un vieillissement en sant\u00e9","datePublished":"2022-09-01T14:00:00+00:00","dateModified":"2023-03-21T15:06:37+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/"},"wordCount":402,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg","keywords":["Chiropratique au Canada","Gestion De La Douleur","Soins Chiropratiques","vieillir en sant\u00e9"],"articleSection":["Vieillir en sant\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/","url":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/","name":"Les soins chiropratiques favorisent un vieillissement en sant\u00e9 - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg","datePublished":"2022-09-01T14:00:00+00:00","dateModified":"2023-03-21T15:06:37+00:00","description":"Avec l\u2019\u00e2ge, nous sommes g\u00e9n\u00e9ralement plus vuln\u00e9rables aux blessures et aux douleurs. Les chiropraticiens canadiens mettent tout en \u0153uvre pour aider les gens \u00e0 vivre une vie plus saine en r\u00e9duisant les risques de chute, de blessure et d\u2019invalidit\u00e9.","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/09\/chiropractic-blog-banner-healthy-aging.jpg","width":1024,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/les-soins-chiropratiques-favorisent-un-vieillissement-en-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Vieillir en sant\u00e9","item":"https:\/\/chiropractic.ca\/fr\/category\/vieillir-en-sante\/"},{"@type":"ListItem","position":3,"name":"Les soins chiropratiques favorisent un vieillissement en sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff","name":"sysadmin"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/71786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/13561"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=71786"}],"version-history":[{"count":2,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/71786\/revisions"}],"predecessor-version":[{"id":71788,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/71786\/revisions\/71788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/70994"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=71786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=71786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=71786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}