{"id":72085,"date":"2023-04-13T13:46:29","date_gmt":"2023-04-13T17:46:29","guid":{"rendered":"https:\/\/chiropractic.ca\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/"},"modified":"2023-06-07T08:18:37","modified_gmt":"2023-06-07T12:18:37","slug":"9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/","title":{"rendered":"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water-1024x576.jpg\" alt=\"femmes exer&#xE7;ant dans l'eau\" class=\"wp-image-72081\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water-1024x576.jpg 1024w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water-400x225.jpg 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water-768x432.jpg 768w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9t\u00e9 est l\u00e0 et les activit\u00e9s aquatiques battent leur plein. Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits. <\/p>\n\n<p class=\"wp-block-paragraph\">Voici neuf avantages \u00e0 faire de l\u2019exercice dans l\u2019eau (le meilleur exercice \u00e9tant la natation) :<\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>Vous souffrez moins de la chaleur :<\/strong> L\u2019entra\u00eenement peut causer des coups de chaleur, particuli\u00e8rement en plein \u00e9t\u00e9. En faisant vos exercices dans l\u2019eau, vous \u00e9vacuez la chaleur plus rapidement et \u00eates moins susceptible de \u00ab surchauffer \u00bb. Si l\u2019eau est chaude, vous ne pourrez pas tellement vous rafra\u00eechir, mais votre circulation sanguine sera meilleure, ce qui est souhaitable quand on fait de l\u2019exercice. <\/li>\n\n\n\n<li><strong>Vous souffrez moins de la chaleur :<\/strong> L\u2019entra\u00eenement peut causer des coups de chaleur, particuli\u00e8rement en plein \u00e9t\u00e9. En faisant vos exercices dans l\u2019eau, vous \u00e9vacuez la chaleur plus rapidement et \u00eates moins susceptible de \u00ab surchauffer \u00bb. Si l\u2019eau est chaude, vous ne pourrez pas tellement vous rafra\u00eechir, mais votre circulation sanguine sera meilleure, ce qui est souhaitable quand on fait de l\u2019exercice.  <\/li>\n\n\n\n<li><strong>L\u2019eau offre un degr\u00e9 de r\u00e9sistance :<\/strong> Comme vous pratiquez vos mouvements dans l\u2019eau plut\u00f4t que dans l\u2019air, vous travaillez plus fort. Cette r\u00e9sistance est id\u00e9ale pour d\u00e9velopper votre force globale et votre endurance. <\/li>\n\n\n\n<li><strong>Vous pouvez ajuster la r\u00e9sistance :<\/strong> Selon votre vitesse, votre position et votre forme dans l\u2019eau, la r\u00e9sistance \u00e0 laquelle vous faites face varie. Par exemple, plus vos mouvements de nage sont hydrodynamiques, plus vite vous irez et moins la r\u00e9sistance sera grande. En revanche, si vous faites du jogging ou de la course dans l\u2019eau, en particulier si vous avez de l\u2019eau au-dessus de la taille, la r\u00e9sistance sera beaucoup plus importante (ce genre d\u2019exercice est souvent conseill\u00e9 si vous voulez am\u00e9liorer votre vitesse de course, votre force et votre endurance sur la terre ferme).  <\/li>\n\n\n\n<li><strong>C\u2019est de plus en plus facile avec le temps :<\/strong> Mieux vous ma\u00eetrisez les techniques de nage, plus vous glissez efficacement dans l\u2019eau, ce qui vous permet de d\u00e9penser moins d\u2019\u00e9nergie et d\u2019efforts tout en allant plus vite. La bonne nouvelle, c\u2019est que plus vous pratiquez et conditionnez votre corps, plus la natation devient facile.  <\/li>\n\n\n\n<li><strong>Vous pouvez int\u00e9grer des pauses :<\/strong> Vous n\u2019avez pas besoin d\u2019interrompre vos exercices dans l\u2019eau pour donner une pause \u00e0 votre corps durant un entra\u00eenement. Si vous nagez, vous pouvez ajouter des \u00ab mouvements de repos \u00bb, comme la marini\u00e8re (nage sur le c\u00f4t\u00e9) ou le dos crawl\u00e9, pendant une minute ou deux (ou une longueur ou deux dans la piscine) jusqu\u2019\u00e0 ce que vous ayez r\u00e9cup\u00e9r\u00e9.  <\/li>\n\n\n\n<li><strong>Vous pouvez augmenter graduellement l\u2019intensit\u00e9 :<\/strong> L\u2019avantage de la natation, c\u2019est que vous pouvez apporter des changements graduels \u00e0 votre routine sans grande difficult\u00e9. Augmentez simplement le temps que vous passez \u00e0 nager, de fa\u00e7on constante, et faites des pauses plus courtes \u2013 ou encore remplacez vos pauses par des mouvements de repos (voir le conseil no6). <\/li>\n\n\n\n<li><strong>C\u2019est id\u00e9al pour maintenir la souplesse des articulations et raffermir les muscles :<\/strong> \u00c9tant donn\u00e9 le faible impact de l\u2019exercice dans l\u2019eau, vos articulations restent souples. De plus, compte tenu de la r\u00e9sistance qu\u2019offre l\u2019eau, vous gardez vos muscles bien fermes. <\/li>\n\n\n\n<li><strong>Tout votre corps est soutenu :<\/strong> Non seulement l\u2019exercice dans l\u2019eau est \u00e0 faible impact, mais il est excellent pour le soutien. Votre dos vous dira merci! En effet, vous n\u2019avez pas \u00e0 vous soucier du poids qu\u2019exerce votre corps sur votre colonne, ni de votre posture lorsque vous vous d\u00e9placez dans l\u2019eau. Si vous n\u2019\u00eates pas un adepte de la natation, vous pouvez quand m\u00eame effectuer des exercices l\u00e9gers dans l\u2019eau : entra\u00eenez-vous \u00e0 marcher dans la piscine, avec de l\u2019eau jusqu\u2019\u00e0 la taille, pour rel\u00e2cher la pression sur vos articulations et votre dos tout en faisant des mouvements.   <\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><br\/>Chassez la pression en allant \u00e0 la piscine ou \u00e0 la plage, et sautez \u00e0 l\u2019eau!<\/p>\n\n<p class=\"wp-block-paragraph\">Consultez votre chiropraticien pour savoir quels types d\u2019exercices vous conviennent.<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/chiropractic.ca\/fr\/trouvez-un-chiropraticien\/\">Trouvez un chiropraticien pr\u00e8s de chez vous<\/a><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.<\/p>\n","protected":false},"author":13561,"featured_media":72082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3007,2997,3122],"tags":[2928,1499,2484],"class_list":["post-72085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-pour-le-dos-au-travail","category-en-jeu","category-expertise-chiropratique","tag-etirements","tag-exercice","tag-mode-de-vie"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-13T17:46:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-07T12:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sysadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"sysadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/\"},\"author\":{\"name\":\"sysadmin\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\"},\"headline\":\"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer\",\"datePublished\":\"2023-04-13T17:46:29+00:00\",\"dateModified\":\"2023-06-07T12:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/benefits-of-exercising-in-water.jpg\",\"keywords\":[\"\u00c9tirements\",\"Exercice\",\"Mode De Vie\"],\"articleSection\":[\"Conseils pour le dos au travail\",\"En jeu\",\"expertise chiropratique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/\",\"name\":\"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/benefits-of-exercising-in-water.jpg\",\"datePublished\":\"2023-04-13T17:46:29+00:00\",\"dateModified\":\"2023-06-07T12:18:37+00:00\",\"description\":\"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/benefits-of-exercising-in-water.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/benefits-of-exercising-in-water.jpg\",\"width\":1200,\"height\":675,\"caption\":\"women exercising in water\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils pour le dos au travail\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/category\\\/conseils-pour-le-dos-au-travail\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/264d37928b3c85144f3ca38232d71cff\",\"name\":\"sysadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/","og_locale":"fr_FR","og_type":"article","og_title":"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer - Association chiropratique canadienne","og_description":"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.","og_url":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2023-04-13T17:46:29+00:00","article_modified_time":"2023-06-07T12:18:37+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg","type":"image\/jpeg"}],"author":"sysadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"sysadmin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/"},"author":{"name":"sysadmin","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff"},"headline":"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer","datePublished":"2023-04-13T17:46:29+00:00","dateModified":"2023-06-07T12:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/"},"wordCount":732,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg","keywords":["\u00c9tirements","Exercice","Mode De Vie"],"articleSection":["Conseils pour le dos au travail","En jeu","expertise chiropratique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/","url":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/","name":"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg","datePublished":"2023-04-13T17:46:29+00:00","dateModified":"2023-06-07T12:18:37+00:00","description":"Que ce soit dans un lac pr\u00e8s de chez vous, \u00e0 la plage ou dans une piscine, parlons un peu des exercices que vous pouvez faire dans l\u2019eau et de leurs bienfaits.","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/04\/benefits-of-exercising-in-water.jpg","width":1200,"height":675,"caption":"women exercising in water"},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/9-avantages-a-faire-de-lexercice-dans-la-piscine-le-lac-ou-la-mer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Conseils pour le dos au travail","item":"https:\/\/chiropractic.ca\/fr\/category\/conseils-pour-le-dos-au-travail\/"},{"@type":"ListItem","position":3,"name":"9 avantages \u00e0 faire de l\u2019exercice dans la piscine, le lac ou la mer"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/264d37928b3c85144f3ca38232d71cff","name":"sysadmin"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/13561"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=72085"}],"version-history":[{"count":1,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72085\/revisions"}],"predecessor-version":[{"id":72086,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72085\/revisions\/72086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/72082"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=72085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=72085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=72085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}