{"id":72465,"date":"2023-05-31T15:04:46","date_gmt":"2023-05-31T19:04:46","guid":{"rendered":"https:\/\/chiropractic.ca\/?p=72465"},"modified":"2023-07-14T15:43:34","modified_gmt":"2023-07-14T19:43:34","slug":"le-pouvoir-du-partenariat","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/","title":{"rendered":"Le pouvoir du partenariat"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/BackMatters_CCRF12_FR.png\" alt=\"\" class=\"wp-image-72467\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/BackMatters_CCRF12_FR.png 1024w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/BackMatters_CCRF12_FR-400x225.png 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/BackMatters_CCRF12_FR-768x432.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab La recherche repr\u00e9sente la monnaie d\u2019\u00e9change de la profession chiropratique \u00bb, dit le Dr Richard Brown, secr\u00e9taire g\u00e9n\u00e9ral de la F\u00e9d\u00e9ration mondiale de la chiropratique \u00c0 la Fondation canadienne pour la recherche en chiropratique (FCRC), nous sommes d\u2019accord avec son point de vue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi? Parce qu\u2019une monnaie d\u2019\u00e9change permet d\u2019\u00eatre largement accept\u00e9. C\u2019est la raison pour laquelle la recherche de grande qualit\u00e9 fond\u00e9e sur des donn\u00e9es probantes est n\u00e9cessaire pour soutenir l\u2019acceptation de notre profession en tant que chef de file dans la prestation des soins de sant\u00e9. Par ailleurs, une monnaie d\u2019\u00e9change facilite certainement les discussions avec les assureurs et les fournisseurs de polices d\u2019assurance, car ces d\u00e9cideurs souhaitent \u00e9changer du soutien financier contre un traitement efficace pour les patients.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Alors, comment appliquons-nous ce concept dynamique de monnaie d\u2019\u00e9change? Et comment augmentons-nous la quantit\u00e9 de recherche que nous pouvons appuyer? Heureusement, la r\u00e9ponse est simple : les partenariats.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail. En effet, des partenaires bien \u00e9tablis peuvent rapidement offrir de nouvelles ressources et comp\u00e9tences \u00e0 un co\u00fbt tr\u00e8s bas, ce que nous pouvons r\u00e9sumer en quelques mots : l\u2019effet de levier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous pouvons tirer profit d\u2019une valeur remarquable en permettant \u00e0 la FCRC de combiner des ressources et des contributions au sein de la profession avec des actifs importants en dehors de la profession.<br>Un bon exemple de cet effet de levier nous touche directement. La FCRC s\u2019est r\u00e9cemment associ\u00e9e \u00e0 la Fondation du Royal College of Chiropractic Sports Sciences \u2013 Canada pour offrir la toute premi\u00e8re demande de propositions canadienne coparrain\u00e9e pour des projets de recherche en sciences du sport. Ce travail de collaboration a entra\u00een\u00e9 une plus grande enveloppe de subvention, les deux fondations ayant aussi fourni un soutien financier. Le r\u00e9sultat net \u00e9tait un montant de 75 000 $ en nouvelles bourses de recherche et une expansion de nos r\u00e9seaux professionnels communs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Je suis tr\u00e8s heureuse du succ\u00e8s de notre demande de propositions coparrain\u00e9e, pr\u00e9cise la Dre Sasha Hamid, pr\u00e9sidente du comit\u00e9 de partenariat. C\u2019est une situation gagnante pour les deux organismes, puisque leurs priorit\u00e9s se sont align\u00e9es pour cr\u00e9er une tr\u00e8s bonne valeur. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Gr\u00e2ce \u00e0 cette initiative, nous avons \u00e9t\u00e9 en mesure de braquer les projecteurs sur d\u2019importantes perc\u00e9es r\u00e9alis\u00e9es par des chercheurs de premier plan en chiropratique du sport \u00e0 l\u2019\u00e9chelle nationale, d\u00e9clare le Dr Richard McIlmoyle, pr\u00e9sident du comit\u00e9 de recherche de la FCRC. Il s\u2019agit, d\u2019une part, d\u2019aider les sportifs \u00e0 am\u00e9liorer leurs performances et \u00e0 revenir au jeu plus rapidement et, d\u2019autre part, de permettre aux chiropraticiens d\u2019acc\u00e9der \u00e0 un module de formation sur le traitement des commotions et \u00e0 une trousse d\u2019outils favorisant le retour au jeu des sportifs parmi leurs clients. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que des investissements financiers soient appr\u00e9ci\u00e9s, les partenaires peuvent apporter un large \u00e9ventail de ressources, telles que soutien en nature, personnel, marketing, transfert de connaissances (p. ex., acc\u00e8s \u00e0 des renseignements de grande valeur), technologie et \u00e9v\u00e9nements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Si la recherche repr\u00e9sente la monnaie d\u2019\u00e9change de la profession, je crois que les partenariats constituent certains des meilleurs investissements que nous pouvons faire. Et ce n\u2019est que le d\u00e9but! pr\u00e9cise la Dre Hamid. Nous avons maintenant conclu des ententes avec la Facult\u00e9 de m\u00e9decine Temerty de l\u2019Universit\u00e9 de Toronto, le Centre d\u2019excellence sur la douleur chronique pour les v\u00e9t\u00e9rans canadiens, la Fondation Chiropratique du Qu\u00e9bec et l\u2019Universit\u00e9 Acadia. L\u2019important, c\u2019est que nous soyons pr\u00eats \u00e0 conna\u00eetre beaucoup de succ\u00e8s gr\u00e2ce \u00e0 nos partenariats, dans le cadre de notre plan strat\u00e9gique de 2023 \u00e0 2025. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Restez \u00e0 l\u2019aff\u00fbt! La FCRC vous communiquera d\u2019autres nouvelles int\u00e9ressantes sur les gains tangibles qui d\u00e9coulent de collaborations bien r\u00e9fl\u00e9chies. Et si vous ne voulez pas attendre \u2013 ou si vous avez une id\u00e9e de partenariat \u2013, n\u2019h\u00e9sitez pas \u00e0 \u00e9crire \u00e0 <a href=\"mailto:info@chiroresearch.ca\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>info@chiroresearch.ca<\/strong><\/a>. Nous aimons recevoir des commentaires de cliniciens de partout au Canada. Vos relations et votre expertise jettent les bases de nos futures r\u00e9ussites.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail. <\/p>\n","protected":false},"author":9,"featured_media":72527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"67226,51041,52583,67228,71576,53371","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3186],"tags":[2266],"class_list":["post-72465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recherche-fr","tag-recherche"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le pouvoir du partenariat - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-31T19:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T19:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Wire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Wire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/\"},\"author\":{\"name\":\"The Wire\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/7cd16deffd5d0a82dec50993c0c17f2e\"},\"headline\":\"Le pouvoir du partenariat\",\"datePublished\":\"2023-05-31T19:04:46+00:00\",\"dateModified\":\"2023-07-14T19:43:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/\"},\"wordCount\":768,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/PowerofPartership_Research-scaled.jpg\",\"keywords\":[\"Recherche\"],\"articleSection\":[\"recherche\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/\",\"name\":\"Le pouvoir du partenariat - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/PowerofPartership_Research-scaled.jpg\",\"datePublished\":\"2023-05-31T19:04:46+00:00\",\"dateModified\":\"2023-07-14T19:43:34+00:00\",\"description\":\"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/PowerofPartership_Research-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/PowerofPartership_Research-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Science, partnership and lab team handshake on collaboration on medical project for innovation in medicine or cancer research. Scientist, teamwork or man meeting and welcome new hiring girl partner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/le-pouvoir-du-partenariat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le pouvoir du partenariat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/7cd16deffd5d0a82dec50993c0c17f2e\",\"name\":\"The Wire\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/","og_locale":"fr_FR","og_type":"article","og_title":"Le pouvoir du partenariat - Association chiropratique canadienne","og_description":"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.","og_url":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2023-05-31T19:04:46+00:00","article_modified_time":"2023-07-14T19:43:34+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg","type":"image\/jpeg"}],"author":"The Wire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"The Wire","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/"},"author":{"name":"The Wire","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/7cd16deffd5d0a82dec50993c0c17f2e"},"headline":"Le pouvoir du partenariat","datePublished":"2023-05-31T19:04:46+00:00","dateModified":"2023-07-14T19:43:34+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/"},"wordCount":768,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg","keywords":["Recherche"],"articleSection":["recherche"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/","url":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/","name":"Le pouvoir du partenariat - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg","datePublished":"2023-05-31T19:04:46+00:00","dateModified":"2023-07-14T19:43:34+00:00","description":"En 2019, la FCRC a d\u00e9cid\u00e9 d\u2019accueillir l\u2019id\u00e9e de s\u2019unir \u00e0 des organismes alli\u00e9s en cr\u00e9ant un comit\u00e9 de partenariat. La raison \u00e9tait simple : il y a des centaines de groupes au Canada qui d\u00e9sirent collaborer avec des fondations de confiance, comme la n\u00f4tre, pour faire avancer leur travail.","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2023\/05\/PowerofPartership_Research-scaled.jpg","width":2560,"height":1706,"caption":"Science, partnership and lab team handshake on collaboration on medical project for innovation in medicine or cancer research. Scientist, teamwork or man meeting and welcome new hiring girl partner"},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/le-pouvoir-du-partenariat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le pouvoir du partenariat"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/7cd16deffd5d0a82dec50993c0c17f2e","name":"The Wire"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=72465"}],"version-history":[{"count":3,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72465\/revisions"}],"predecessor-version":[{"id":72708,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/72465\/revisions\/72708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/72527"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=72465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=72465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=72465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}