{"id":73975,"date":"2024-06-27T11:36:26","date_gmt":"2024-06-27T15:36:26","guid":{"rendered":"https:\/\/chiropractic.ca\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/"},"modified":"2024-06-27T11:52:30","modified_gmt":"2024-06-27T15:52:30","slug":"dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales","status":"publish","type":"post","link":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/","title":{"rendered":"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-1024x768.jpg\" alt=\"Dr Ryan Coster\" class=\"wp-image-73972\" srcset=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-1024x768.jpg 1024w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-400x300.jpg 400w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-768x576.jpg 768w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-1536x1152.jpg 1536w, https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et secr\u00e9taire-tr\u00e9sorier, lui permet de garder les yeux sur l\u2019avenir de la chiropratique \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Il a obtenu son doctorat en chiropratique de la Macquarie University \u00e0 Sydney, en Australie, avec une tr\u00e8s grande distinction et les meilleurs r\u00e9sultats de sa classe.<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Il a \u00e9t\u00e9 attir\u00e9 par le mod\u00e8le de soins int\u00e9gr\u00e9s de son universit\u00e9 : \u00ab Nous avons effectu\u00e9 notre formation aux c\u00f4t\u00e9s de divers professionnels de la sant\u00e9 et nous avons eu l\u2019occasion de d\u00e9couvrir d\u2019autres disciplines m\u00e9dicales, plus particuli\u00e8rement lors de l\u2019\u00e9tude de l\u2019anatomie. C\u2019\u00e9tait donc un mod\u00e8le d\u2019apprentissage vraiment collaboratif. \u00bb<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Aujourd\u2019hui, il exerce dans une clinique enti\u00e8rement interprofessionnelle \u00e0 Moncton, au Nouveau-Brunswick. \u00ab Je mets en pratique ce que je pr\u00f4ne \u00bb, dit-il. Le Dr Coster affirme avoir instaur\u00e9 l\u2019une des plus grandes cliniques multidisciplinaires de la province : \u00ab Mon objectif est de travailler efficacement en faveur de la sant\u00e9 musculosquelettique de toute la population du Nouveau-Brunswick et de faire des chiropraticiens des acteurs \u00e0 part enti\u00e8re de la collaboration interprofessionnelle. \u00bb   <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Outre sa r\u00e9cente \u00e9lection au conseil de la FMC, le Dr Coster a si\u00e9g\u00e9 au conseil d\u2019administration de Chiropractic Australia, a \u00e9t\u00e9 membre de Sports Medicine Australia et est pr\u00e9sident de l\u2019Association des chiropraticiens du Nouveau-Brunswick depuis 2018. En 2022, il a re\u00e7u la prestigieuse M\u00e9daille du jubil\u00e9 de diamant de la Reine Elizabeth II pour ses services exceptionnels dans le domaine des soins de sant\u00e9, et s\u2019est vu d\u00e9cerner le Prix de l\u2019engagement public de l\u2019ACC en 2024 pour ses efforts exceptionnels de repr\u00e9sentation de la profession chiropratique au Canada. <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Le Dr Coster a une vision claire de l\u2019avenir des soins chiropratiques : \u00ab En tant que professionnels, nous devons \u00e9voluer vers des approches fond\u00e9es sur des donn\u00e9es probantes, ax\u00e9es sur le patient, interprofessionnelles et \u2013 l\u2019aspect que je pr\u00e9f\u00e8re \u2013 collaboratives [ou EPIC, pour Evidence-based, Patient-centred, Interprofessional and Collaborative approaches to spine care]. Si nous voulons aller de l\u2019avant, nous devons mieux tirer parti des autres professions de la sant\u00e9 et encourager l\u2019\u00e9tablissement de liens afin de faire progresser les soins de sant\u00e9 dans leur ensemble. \u00bb <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Pour le Dr Coster, les soins int\u00e9gr\u00e9s consistent \u00e0 miser sur les soins collaboratifs : \u00ab L\u2019approche cloisonn\u00e9e est d\u00e9su\u00e8te et date d\u2019une \u00e9poque sombre. Les professionnels de la sant\u00e9 ne doivent pas n\u00e9cessairement tous travailler dans le m\u00eame cabinet, explique-t-il au sujet de sa pratique, mais la collaboration entre les chiropraticiens, les massoth\u00e9rapeutes, les m\u00e9decins de famille, les radiologues, les physioth\u00e9rapeutes, les kin\u00e9siologues, etc., permet de placer plus facilement le patient au centre de notre attention. \u00bb  <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Le Dr Coster invite les leaders de la chiropratique \u00e0 cerner et \u00e0 surmonter les obstacles potentiels au progr\u00e8s, tels qu\u2019une m\u00e9thodologie clinique d\u00e9pass\u00e9e, et \u00e0 encourager les organismes de r\u00e9glementation \u00e0 faire pression sur les gouvernements qui permettent aux chiropraticiens de mettre \u00e0 profit l\u2019ensemble de leur champ de comp\u00e9tences, \u00ab car il y a souvent des formalit\u00e9s administratives inutiles qui nous emp\u00eachent d\u2019offrir les meilleurs soins aux patients : les soins collaboratifs. \u00bb<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>Il invite \u00e9galement les chiropraticiens \u00e0 adopter une vision mondiale : \u00ab Certains mod\u00e8les de soins de sant\u00e9 sont plus efficaces que d\u2019autres. Nous devrions examiner les programmes pilotes et les autres programmes de soins collaboratifs propos\u00e9s dans d\u2019autres pays ou r\u00e9gions du monde. \u00bb <\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>\u00ab Il est essentiel que les chiropraticiens aient toujours leur mot \u00e0 dire dans les discussions de haut niveau sur les soins de sant\u00e9, car s\u2019ils ne sont pas assis \u00e0 la table, ils seront probablement au menu, indique-t-il \u00e0 propos du lobbying aupr\u00e8s du gouvernement et des relations avec les parties prenantes.<\/p>\n\n<p class=\"wp-block-paragraph\"><br\/>\u00ab Ma priorit\u00e9 est de faciliter le partage des connaissances entre les nations, poursuit-il, car le succ\u00e8s de la chiropratique au Canada, par exemple, pourrait aider d\u2019autres pays qui ont besoin de telles connaissances. Au Canada, nous avons la chance de disposer d\u2019excellentes lignes directrices gr\u00e2ce au PCGC, qui peuvent \u00eatre diffus\u00e9es \u00e0 grande \u00e9chelle, et je pense qu\u2019elles seraient facilement adopt\u00e9es partout dans le monde. C\u2019est ce genre de travail qui d\u00e9montre que nous collaborons r\u00e9ellement en nous tournant vers l\u2019avenir, et que les autres pays n\u2019ont pas \u00e0 r\u00e9inventer la roue pour faire progresser notre profession. \u00bb  <br\/><\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab Mon but ultime est de contribuer \u00e0 l\u2019avancement de la chiropratique gr\u00e2ce \u00e0 la promotion du mod\u00e8le \u201cEPIC\u201d \u00e0 l\u2019\u00e9chelle mondiale, afin d\u2019offrir une exp\u00e9rience optimis\u00e9e et centr\u00e9e sur la personne \u00e0 tous ceux et celles que nous servons \u00bb, conclut-il.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et secr\u00e9taire-tr\u00e9sorier, lui permet de garder les yeux sur l\u2019avenir de la chiropratique \u00e0 l\u2019\u00e9chelle mondiale. Il a obtenu son doctorat en chiropratique de la Macquarie University \u00e0 Sydney, en Australie, [&hellip;]<\/p>\n","protected":false},"author":13548,"featured_media":73973,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[3122],"tags":[2483,2933],"class_list":["post-73975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expertise-chiropratique","tag-chiropraticien-en-vedette","tag-chiropratique-au-canada"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association chiropratique canadienne<\/title>\n<meta name=\"description\" content=\"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales - Association chiropratique canadienne\" \/>\n<meta property=\"og:description\" content=\"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/\" \/>\n<meta property=\"og:site_name\" content=\"Association chiropratique canadienne\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T15:36:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-27T15:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone Lai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone Lai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/\"},\"author\":{\"name\":\"Simone Lai\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/65541086616f2a78953a552aa305e368\"},\"headline\":\"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales\",\"datePublished\":\"2024-06-27T15:36:26+00:00\",\"dateModified\":\"2024-06-27T15:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/\"},\"wordCount\":823,\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Dr.-Ryan-Coster-photo-scaled.jpg\",\"keywords\":[\"Chiropraticien(ne) En Vedette\",\"Chiropratique au Canada\"],\"articleSection\":[\"expertise chiropratique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/\",\"name\":\"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales - Association chiropratique canadienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Dr.-Ryan-Coster-photo-scaled.jpg\",\"datePublished\":\"2024-06-27T15:36:26+00:00\",\"dateModified\":\"2024-06-27T15:52:30+00:00\",\"description\":\"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Dr.-Ryan-Coster-photo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Dr.-Ryan-Coster-photo-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Dr. Ryan Coster\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"expertise chiropratique\",\"item\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/category\\\/expertise-chiropratique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"name\":\"Association chiropratique canadienne\",\"description\":\"Chiropractors helping Canadians live healthier lives\",\"publisher\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#organization\",\"name\":\"Association chiropratique canadienne\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"contentUrl\":\"https:\\\/\\\/chiropractic.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cca-logo.svg\",\"width\":921,\"height\":250,\"caption\":\"Association chiropratique canadienne\"},\"image\":{\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chiropractic.ca\\\/fr\\\/#\\\/schema\\\/person\\\/65541086616f2a78953a552aa305e368\",\"name\":\"Simone Lai\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association chiropratique canadienne","description":"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/","og_locale":"fr_FR","og_type":"article","og_title":"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales - Association chiropratique canadienne","og_description":"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et","og_url":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/","og_site_name":"Association chiropratique canadienne","article_published_time":"2024-06-27T15:36:26+00:00","article_modified_time":"2024-06-27T15:52:30+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg","type":"image\/jpeg"}],"author":"Simone Lai","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Simone Lai","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#article","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/"},"author":{"name":"Simone Lai","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/65541086616f2a78953a552aa305e368"},"headline":"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales","datePublished":"2024-06-27T15:36:26+00:00","dateModified":"2024-06-27T15:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/"},"wordCount":823,"publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg","keywords":["Chiropraticien(ne) En Vedette","Chiropratique au Canada"],"articleSection":["expertise chiropratique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/","url":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/","name":"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales - Association chiropratique canadienne","isPartOf":{"@id":"https:\/\/chiropractic.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#primaryimage"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#primaryimage"},"thumbnailUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg","datePublished":"2024-06-27T15:36:26+00:00","dateModified":"2024-06-27T15:52:30+00:00","description":"Le nouveau poste du Dr Ryan Coster \u00e0 titre de vice-pr\u00e9sident de la FMC, o\u00f9 il a auparavant \u00e9t\u00e9 repr\u00e9sentant canadien du conseil d\u2019administration et","breadcrumb":{"@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#primaryimage","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2024\/06\/Dr.-Ryan-Coster-photo-scaled.jpg","width":2560,"height":1920,"caption":"Dr. Ryan Coster"},{"@type":"BreadcrumbList","@id":"https:\/\/chiropractic.ca\/fr\/dr-ryan-coster-un-chiropraticien-aux-ambitions-mondiales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chiropractic.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"expertise chiropratique","item":"https:\/\/chiropractic.ca\/fr\/category\/expertise-chiropratique\/"},{"@type":"ListItem","position":3,"name":"Dr Ryan Coster \u2013 un chiropraticien aux ambitions mondiales"}]},{"@type":"WebSite","@id":"https:\/\/chiropractic.ca\/fr\/#website","url":"https:\/\/chiropractic.ca\/fr\/","name":"Association chiropratique canadienne","description":"Chiropractors helping Canadians live healthier lives","publisher":{"@id":"https:\/\/chiropractic.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chiropractic.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/chiropractic.ca\/fr\/#organization","name":"Association chiropratique canadienne","url":"https:\/\/chiropractic.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","contentUrl":"https:\/\/chiropractic.ca\/wp-content\/uploads\/2022\/08\/cca-logo.svg","width":921,"height":250,"caption":"Association chiropratique canadienne"},"image":{"@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/chiropractic.ca\/fr\/#\/schema\/person\/65541086616f2a78953a552aa305e368","name":"Simone Lai"}]}},"_links":{"self":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/73975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/users\/13548"}],"replies":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/comments?post=73975"}],"version-history":[{"count":1,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/73975\/revisions"}],"predecessor-version":[{"id":73976,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/posts\/73975\/revisions\/73976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media\/73973"}],"wp:attachment":[{"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/media?parent=73975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/categories?post=73975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chiropractic.ca\/fr\/wp-json\/wp\/v2\/tags?post=73975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}